{"id":435,"date":"2023-01-08T13:10:44","date_gmt":"2023-01-08T13:10:44","guid":{"rendered":"https:\/\/brutalfm.net\/?p=435"},"modified":"2023-01-08T13:10:45","modified_gmt":"2023-01-08T13:10:45","slug":"la-udc-inicia-reparto-masivo-de-juguetes-dandole-continuidad-al-programa-sonrisas-por-juguetes-en-el-sector-la-cienaga","status":"publish","type":"post","link":"https:\/\/brutalfm.net\/index.php\/2023\/01\/08\/la-udc-inicia-reparto-masivo-de-juguetes-dandole-continuidad-al-programa-sonrisas-por-juguetes-en-el-sector-la-cienaga\/","title":{"rendered":"La \u2013UDC- inicia Reparto masivo de juguetes d\u00e1ndole continuidad al Programa sonrisas por juguetes en el sector La Ci\u00e9naga."},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"La \u2013UDC  inicia Reparto masivo de juguetes d\u00e1ndole continuidad al Programa sonrisas por juguetes en\" width=\"618\" height=\"348\" src=\"https:\/\/www.youtube.com\/embed\/5xWhhCMHI9Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">SANTO DOMINGO, DN.- Por motivo del D\u00eda de los Santos Reyes Magos, El presidente del Partido Uni\u00f3n Dem\u00f3crata Cristiana (UDC), Luis Acosta Moreta \u00abEl Gallo\u00bb, inici\u00f3 el programa sonrisas por juguetes a miles de ni\u00f1os y ni\u00f1as del Pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada que durar\u00e1 7 d\u00edas inici\u00f3 este 6 de enero en la Escuelita Sonrisa Familiar en el Barrio La Ci\u00e9naga, donde cientos de ni\u00f1os recibieron con emoci\u00f3n sus juguetes, continuar\u00e1 ma\u00f1ana 7 en la Parada de Motoconchitas del Km.12 de Haina, el lunes 9 en Hatillo de Azua, luego en Villas Agr\u00edcolas La Nueva \u00abBarquita\u00bb, y continuar\u00e1 en diferentes sectores del gran Santo Domingo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infantes de todas las edades recibieron mu\u00f1eca, juegos educativos, bolas de baloncesto, bicicletas, bates, patinetas entre otros, al tiempo que los ni\u00f1os pudieron disfrutar de helados, paleta y palomitas de ma\u00edz algod\u00f3n de az\u00facar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, el presidente de la (UDC), expres\u00f3 entendemos que el d\u00eda m\u00e1s dif\u00edcil de la sociedad Dominicana es el DIA de Reyes debido a que el ni\u00f1o que sale a jugar por la ma\u00f1ana y no tiene su juguete cuestiona a sus Padres, al T\u00edo, al vecino porque \u00e9l entiende que se port\u00f3 bien y av\u00eda que gratificarlo con un juguete, y sobre todo genera el sentimiento m\u00e1s da\u00f1ino que es la envidia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debemos cuidar la inocencia de los ni\u00f1os que es la garant\u00eda que tenemos para que sean hombres de bien. Siempre, y cuando, se cr\u00eden con valores morales, y \u00e9tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEn esta jornada que realizamos cada a\u00f1o se multiplican m\u00e1s ni\u00f1os en esta ocasi\u00f3n estamos impactando a miles de ni\u00f1os de cada uno de los sectores m\u00e1s vulnerables de nuestro pa\u00eds. Por lo que esperamos seguir llevando alegr\u00eda y cambiando sonrisas por juguetes\u00bb, manifest\u00f3 (El Gallo).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-La \u2013UDC- Y \u2013FREDOCO\u2010 llevan m\u00e1s de 20 a\u00f1os realizando esta obra, con el objetivo de compartir la magia de los Reyes Magos con ni\u00f1os y ni\u00f1as m\u00e1s necesitados provenientes de los barrios m\u00e1s vulnerables de todo el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO, DN.- Por motivo del D\u00eda de los Santos Reyes Magos, El presidente del Partido Uni\u00f3n Dem\u00f3crata Cristiana (UDC), Luis Acosta Moreta \u00abEl Gallo\u00bb, inici\u00f3 el programa sonrisas por juguetes a miles de ni\u00f1os y ni\u00f1as del Pa\u00eds. La jornada que durar\u00e1 7 d\u00edas inici\u00f3 este 6 de enero en la Escuelita Sonrisa Familiar &hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-435","post","type-post","status-publish","format-standard","","category-merengue"],"_links":{"self":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/comments?post=435"}],"version-history":[{"count":1,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/435\/revisions"}],"predecessor-version":[{"id":436,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/435\/revisions\/436"}],"wp:attachment":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/media?parent=435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/categories?post=435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/tags?post=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}