{"id":588,"date":"2023-11-15T17:36:48","date_gmt":"2023-11-15T17:36:48","guid":{"rendered":"https:\/\/brutalfm.net\/?p=588"},"modified":"2023-11-15T17:36:49","modified_gmt":"2023-11-15T17:36:49","slug":"caso-de-colombiano-muerto-por-policia-dominicana-embajada-colombiana-dice-le-da-seguimiento","status":"publish","type":"post","link":"https:\/\/brutalfm.net\/index.php\/2023\/11\/15\/caso-de-colombiano-muerto-por-policia-dominicana-embajada-colombiana-dice-le-da-seguimiento\/","title":{"rendered":"Caso de colombiano muerto por polic\u00eda dominicana; Embajada colombiana dice le da seguimiento"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li>El cuerpo del extranjero no ha sido reclamado por parientes<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"896\" height=\"504\" src=\"https:\/\/brutalfm.net\/wp-content\/uploads\/2023\/11\/identificacion-del-colombiano-focus-0-0-896-504.jpg\" alt=\"\" class=\"wp-image-589\" srcset=\"https:\/\/brutalfm.net\/wp-content\/uploads\/2023\/11\/identificacion-del-colombiano-focus-0-0-896-504.jpg 896w, https:\/\/brutalfm.net\/wp-content\/uploads\/2023\/11\/identificacion-del-colombiano-focus-0-0-896-504-300x169.jpg 300w, https:\/\/brutalfm.net\/wp-content\/uploads\/2023\/11\/identificacion-del-colombiano-focus-0-0-896-504-768x432.jpg 768w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><figcaption>Seg\u00fan la Polic\u00eda, al acusado secuestrador colombiano se le ocup\u00f3 en su mano derecha un rev\u00f3lver calibre 38, serie No. 5757, dijo la Polic\u00eda. (<strong>FUENTE EXTERNA<\/strong>)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>Embajada<\/strong>&nbsp;de&nbsp;<strong>Colombia<\/strong>&nbsp;en Rep\u00fablica Dominicana trabaja en el caso del&nbsp;<strong>colombiano<\/strong>&nbsp;que fue&nbsp;<strong>ultimado<\/strong>&nbsp;el lunes por agentes de la&nbsp;<strong>Polic\u00eda Nacional<\/strong>&nbsp;en medio de un \u00abintercambio de disparos\u00bb mientras rescataban a una adolescente y a otra persona que \u00e9ste alegadamente ten\u00eda secuestrados en el sector R\u00edo Arriba en Ban\u00ed, provincia Peravia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jhon Fredy M\u00e9ndez Arrieta<\/strong>, de 36 a\u00f1os,&nbsp;<strong>recibi\u00f3 cuatro disparos en el t\u00f3rax<\/strong>, uno de estos con salida. Su&nbsp;<strong>cad\u00e1ver<\/strong>&nbsp;permanece en la&nbsp;<strong>morgue<\/strong>&nbsp;de la provincia de Azua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pese a que la\u00a0<strong>embajada<\/strong>\u00a0no ofreci\u00f3 muchas declaraciones al respecto, afirm\u00f3 a\u00a0<strong><em>Diario Libre<\/em><\/strong>\u00a0que s\u00ed tienen el caso y que se har\u00e1n cargo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">No han reclamado cad\u00e1ver<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el momento ning\u00fan\u00a0<strong>familiar<\/strong>\u00a0se ha comunicado con las\u00a0<strong>autoridades\u00a0dominicanas<\/strong>\u00a0para reclamar el\u00a0<strong>cad\u00e1ver<\/strong>. Seg\u00fan inform\u00f3\u00a0<strong>Walter L\u00f3pez<\/strong>, m\u00e9dico legista actuante, el cuerpo puede estar en la\u00a0<strong>morgue<\/strong>\u00a0de cinco a siete d\u00edas, de pasar este plazo, ser\u00e1 sepultado en una fosa com\u00fan debido a que la nevera no tiene la capacidad para tenerlo por m\u00e1s tiempo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el&nbsp;<strong>informe<\/strong>&nbsp;de la instituci\u00f3n del&nbsp;<strong>orden<\/strong>, el&nbsp;<strong>colombiano<\/strong>&nbsp;hab\u00eda secuestrado a la menor, de quien se resguarda su nombre por asuntos legales, al igual que a otra persona. La adolescente reside en Villa Tapia, provincia Hermanas Mirabal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al conversar con algunos comunitarios del sector R\u00edo Arriba, estos manifestaron a&nbsp;<strong><em>Diario Libre<\/em><\/strong>&nbsp;no conocer absolutamente nada sobre el&nbsp;<strong>colombiano<\/strong>&nbsp;y que nunca lo hab\u00edan visto en la&nbsp;<strong>zona<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las&nbsp;<strong>autoridades<\/strong>&nbsp;de la&nbsp;<strong>Polic\u00eda Nacional<\/strong>&nbsp;investigan a fondo el caso para dar con otros posibles responsables involucrados en el rapto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El cuerpo del extranjero no ha sido reclamado por parientes Seg\u00fan la Polic\u00eda, al acusado secuestrador colombiano se le ocup\u00f3 en su mano derecha un rev\u00f3lver calibre 38, serie No. 5757, dijo la Polic\u00eda. (FUENTE EXTERNA) La&nbsp;Embajada&nbsp;de&nbsp;Colombia&nbsp;en Rep\u00fablica Dominicana trabaja en el caso del&nbsp;colombiano&nbsp;que fue&nbsp;ultimado&nbsp;el lunes por agentes de la&nbsp;Polic\u00eda Nacional&nbsp;en medio de un \u00abintercambio &hellip;<\/p>\n","protected":false},"author":3,"featured_media":589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-588","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-america-latina"],"_links":{"self":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/comments?post=588"}],"version-history":[{"count":1,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/588\/revisions"}],"predecessor-version":[{"id":590,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/588\/revisions\/590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/media\/589"}],"wp:attachment":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/media?parent=588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/categories?post=588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/tags?post=588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}