{"id":840,"date":"2025-05-16T22:04:23","date_gmt":"2025-05-16T22:04:23","guid":{"rendered":"https:\/\/brutalfm.net\/?p=840"},"modified":"2025-05-16T22:04:24","modified_gmt":"2025-05-16T22:04:24","slug":"coe-mantiene-16-provincias-bajo-alerta-por-lluvias-y-riesgo-de-inundaciones","status":"publish","type":"post","link":"https:\/\/brutalfm.net\/index.php\/2025\/05\/16\/coe-mantiene-16-provincias-bajo-alerta-por-lluvias-y-riesgo-de-inundaciones\/","title":{"rendered":"COE mantiene 16 provincias bajo alerta por lluvias y riesgo de inundaciones"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/brutalfm.net\/wp-content\/uploads\/2025\/05\/image-12-1024x683.png\" alt=\"\" class=\"wp-image-841\" srcset=\"https:\/\/brutalfm.net\/wp-content\/uploads\/2025\/05\/image-12-1024x683.png 1024w, https:\/\/brutalfm.net\/wp-content\/uploads\/2025\/05\/image-12-300x200.png 300w, https:\/\/brutalfm.net\/wp-content\/uploads\/2025\/05\/image-12-768x512.png 768w, https:\/\/brutalfm.net\/wp-content\/uploads\/2025\/05\/image-12.png 1030w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Centro de Operaciones de Emergencias (<a href=\"https:\/\/www.coe.gob.do\/\" target=\"_blank\" rel=\"noreferrer noopener\">COE<\/a>) inform\u00f3 este jueves que mantiene siete provincias en alerta amarilla y nueve en alerta verde, debido a la persistencia de lluvias que podr\u00edan provocar inundaciones urbanas y rurales, crecidas de r\u00edos, arroyos y ca\u00f1adas, as\u00ed como deslizamientos de tierra.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En alerta amarilla se encuentran las provincias:<strong>\u00a0Monte Plata, S\u00e1nchez Ram\u00edrez, Duarte (especialmente el Bajo Yuna), San Crist\u00f3bal, Mar\u00eda Trinidad S\u00e1nchez, San Jos\u00e9 de Ocoa y el Distrito Nacional.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que en alerta verde est\u00e1n: Santo Domingo, El Seibo, El\u00edas Pi\u00f1a, Peravia, Hato Mayor, La Romana, Saman\u00e1, La Altagracia y San Pedro de Macor\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El COE exhort\u00f3 a la poblaci\u00f3n a no cruzar r\u00edos, arroyos ni ca\u00f1adas que presenten alto volumen de agua, ni utilizar balnearios debido a la fuerte corriente y turbiedad que a\u00fan mantienen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, pidi\u00f3 a los padres y tutores vigilar a sus hijos para evitar accidentes en cuerpos de agua, y a los conductores tomar precauciones debido a la reducci\u00f3n de visibilidad por las lluvias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades instaron a los residentes en zonas vulnerables, especialmente cerca de r\u00edos y terrenos inestables, a mantenerse atentos a los boletines oficiales y seguir las orientaciones de los organismos de protecci\u00f3n civil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para reportes y asistencia, el COE record\u00f3 que pueden comunicarse a los tel\u00e9fonos 809-472-0909, al 911, o al *462 de la OGTIC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las personas deben abstenerse de cruzar r\u00edos, arroyos y ca\u00f1adas que presenten alto<br>vol\u00famenes de agua, no hacer uso de balnearios, en las provincias bajo alerta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Centro de Operaciones de Emergencias (COE) inform\u00f3 este jueves que mantiene siete provincias en alerta amarilla y nueve en alerta verde, debido a la persistencia de lluvias que podr\u00edan provocar inundaciones urbanas y rurales, crecidas de r\u00edos, arroyos y ca\u00f1adas, as\u00ed como deslizamientos de tierra. En alerta amarilla se encuentran las provincias:\u00a0Monte Plata, S\u00e1nchez &hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-840","post","type-post","status-publish","format-standard","","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":1,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/840\/revisions"}],"predecessor-version":[{"id":842,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/posts\/840\/revisions\/842"}],"wp:attachment":[{"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/media?parent=840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/categories?post=840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brutalfm.net\/index.php\/wp-json\/wp\/v2\/tags?post=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}